{"id":2148,"date":"2023-05-18T16:12:46","date_gmt":"2023-05-18T14:12:46","guid":{"rendered":"https:\/\/songesdevigne.com\/?page_id=2148"},"modified":"2023-06-02T17:11:50","modified_gmt":"2023-06-02T15:11:50","slug":"activites","status":"publish","type":"page","link":"https:\/\/songesdevigne.com\/index.php\/activites\/","title":{"rendered":"Activit\u00e9s"},"content":{"rendered":"\n<p class=\"has-theme-palette-8-background-color has-text-color has-background wp-block-paragraph\" style=\"color:#405d8a;font-size:22px\">Activit\u00e9s<\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>Activit\u00e9s sportives<\/strong><\/p>\n\n\n\n<p class=\"has-text-align-left has-theme-palette-5-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Visite en v\u00e9lo \u00e9lectrique<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:18px\"><strong>A 9km (10min)<\/strong> <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>V\u00e9lo Via Dor\u00e9e<\/strong> vous propose ses v\u00e9los \u00e9lectriques (VTT ou VTC) pour des visites du Beaujolais pour tout le monde sans fatigues.<br>Surnomm\u00e9 \u00ab\u00a0la petite Toscane\u00a0\u00bb, le Beaujolais offre un concentr\u00e9 de paysages, d&rsquo;histoire et de gastronomie.<br>Au coeur des villages des pierres dor\u00e9es, <strong>V\u00e9lo Via Dor\u00e9es<\/strong> vous propose de venir d\u00e9couvrir en famille ou entre amis les richesses de notre patrimoine.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Venez prendre un bol d&rsquo;air \u00e0 moins de 40 minutes de Lyon. Nous sommes \u00e0 votre disposition pour vous conseiller sur les sites \u00e0 ne pas manquer, les caveaux pour d\u00e9guster sans oublier les restaurants pour vous requinquer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>A partir de 40\u20ac\/pers<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Appelez : <\/strong>04 37 64 61 28<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Mail : <\/strong><a href=\"http:\/\/vvdor\u00e9es@gmail.com\">vvdor\u00e9es@gmail.com<\/a><\/p>\n\n\n\n<p class=\"has-theme-palette-4-color has-text-color has-medium-font-size wp-block-paragraph\"><strong>Montgolfi\u00e8re<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:18px\"><strong>A 5 km (5 mn)<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Contemplez les merveilleux paysages au nord de Lyon lors d&rsquo;un bapt\u00eame en montgolfi\u00e8re ! Depuis l&rsquo;imposant ballon, vous profitez d&rsquo;un vol magique au-dessus du vignoble du Beaujolais. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vous contemplez les paysages naturels et le patrimoine aux alentours.<\/p>\n\n\n\n<p class=\"has-theme-palette-3-color has-text-color wp-block-paragraph\"><a href=\"https:\/\/www.sport-decouverte.com\/vol-montgolfiere-beaujolais-proche-lyon.html\" target=\"_blank\" rel=\"noreferrer noopener\">En savoir plus &gt;<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\"><strong>Tourisme<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Village de Oingt<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A 7 minutes de nos chambres d\u2019h\u00f4tes, <strong>Oingt<\/strong> est \u00e9lu le plus beau village du Rh\u00f4ne. De son pass\u00e9 m\u00e9di\u00e9val, la cit\u00e9 en a conserv\u00e9 l\u2019ambiance et plusieurs monuments.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Oingt<\/strong> est le seul village du d\u00e9partement \u00e0 \u00eatre r\u00e9pertori\u00e9 parmi les \u00ab&nbsp;Plus Beaux Villages de France&nbsp;\u00bb. Ce<strong> village m\u00e9di\u00e9val <\/strong>perch\u00e9 et fortifi\u00e9 offre \u00e0 ses visiteurs un voyage hors du temps. Ses petites ruelles moyen\u00e2geuses, ses monuments historiques class\u00e9s et restaur\u00e9s font tout <strong>son charme<\/strong>. Promenez-vous dans ses ruelles aux noms bucoliques et d\u00e9couvrez de tr\u00e8s belles demeures en pierres dor\u00e9es. Des cr\u00e9ateurs ou artisans ont install\u00e9 leur atelier et leur magasin d\u2019exposition dans le village. <strong>Surtout, ne manquez pas la Tour d\u2019Oingt, l\u2019\u00e9glise Saint-Mathieu et l\u2019Espace de Musique m\u00e9canique<\/strong>. Prenez rendez-vous pour les moments forts de l\u2019ann\u00e9e : Festival de Musique m\u00e9canique le premier week-end de septembre,&nbsp;cr\u00e8ches de No\u00ebl \u00e0 d\u00e9couvrir dans tout le village, \u00e0 partir du 8 d\u00e9cembre, expositions temporaires \u00e0 la Maison Commune (demeure du XVe si\u00e8cle).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a rel=\"noreferrer noopener\" href=\"https:\/\/www.destination-beaujolais.com\/\" target=\"_blank\">En savoir plus<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Geopark Beaujolais<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le <strong>Geopark Beaujolais<\/strong> vous propose une visite agr\u00e9able et un paysage \u00e9poustouflant. Ses am\u00e9nagements favorisent \u00e0 la fois pr\u00e9servation, d\u00e9couverte et m\u00e9diation scientifique et culturelle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;<a href=\"https:\/\/www.destination-beaujolais.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">En savoir plus<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Les ch\u00e2teaux et jardins du Beaujolais<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019histoire du Beaujolais vous entra\u00eenera sur les traces de nombreux <strong>ch\u00e2teaux<\/strong> mill\u00e9naires: Rochebonne, Rapetour, Bagnols, Montmelas, Jarnioux, La Chaize, Corcelles, Pizay (\u2026) <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ne manquez aucune p\u00e9pite du Beaujolais class\u00e9e Monument Historique \u00e0 visiter.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.destination-beaujolais.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">En savoir plus<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Destination Beaujolais<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bienvenue sur la page officielle de <strong>l&rsquo;Office de Tourisme du Beaujolais!<\/strong> Tous les bons plans pour passer un s\u00e9jour r\u00e9ussi en Beaujolais Balades, Visites, D\u00e9couvertes\u2026 C\u2019est \u00e0 vous de jouer !<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"https:\/\/www.destination-beaujolais.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">En savoir plus<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aux environs imm\u00e9diats du vignoble, <strong>Villefranche-sur-sa\u00f4ne<\/strong>, capitale du <strong>Beaujolais<\/strong>, promet de belles d\u00e9couvertes : culture, patrimoine, gastronomie, f\u00eate du beaujolais nouveau, shopping, le <strong>march\u00e9 de Villefranche<\/strong>\u2026<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lyon, notre voisine<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Lyon<\/strong>, ville travers\u00e9e par deux cours d\u2019eau, le Rh\u00f4ne et la Sa\u00f4ne, prend d\u2019embl\u00e9e un attrait particulier, celui des berges et des quais, des promenades, des r\u00eaveries en terrasse, des croisi\u00e8res\u2026 Une certaine douceur de vivre et une histoire.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">D\u00e9couvrez les charmes et atouts de <strong>Lyon<\/strong>, cit\u00e9 internationale charg\u00e9e d\u2019histoire et de culture, capitale gastronomique ( le Vieux Lyon, Fourvi\u00e8re, le Parc de la T\u00eate d\u2019Or, les berges du Rh\u00f4ne, les mus\u00e9es, la f\u00eate des Lumi\u00e8res chaque 8 d\u00e9cembre\u2026)<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Tout votre programme sur :<br><a href=\"http:\/\/www.tourismepierresdorees.com\">www.tourismepierresdorees.com<\/a><br><a href=\"http:\/\/www.villefranche-beaujolais.fr\">www.villefranche-beaujolais.fr<\/a><br><a href=\"http:\/\/www.rhonetourisme.com\">www.rhonetourisme.com<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Activit\u00e9s Activit\u00e9s sportives Visite en v\u00e9lo \u00e9lectrique A 9km (10min) V\u00e9lo Via Dor\u00e9e vous propose ses v\u00e9los \u00e9lectriques (VTT ou VTC) pour des visites du Beaujolais pour tout le monde sans fatigues.Surnomm\u00e9 \u00ab\u00a0la petite Toscane\u00a0\u00bb, le Beaujolais offre un concentr\u00e9 de paysages, d&rsquo;histoire et de gastronomie.Au coeur des villages des pierres dor\u00e9es, V\u00e9lo Via Dor\u00e9es&#8230;<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"footnotes":""},"class_list":["post-2148","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/songesdevigne.com\/index.php\/wp-json\/wp\/v2\/pages\/2148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/songesdevigne.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/songesdevigne.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/songesdevigne.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/songesdevigne.com\/index.php\/wp-json\/wp\/v2\/comments?post=2148"}],"version-history":[{"count":2,"href":"https:\/\/songesdevigne.com\/index.php\/wp-json\/wp\/v2\/pages\/2148\/revisions"}],"predecessor-version":[{"id":2199,"href":"https:\/\/songesdevigne.com\/index.php\/wp-json\/wp\/v2\/pages\/2148\/revisions\/2199"}],"wp:attachment":[{"href":"https:\/\/songesdevigne.com\/index.php\/wp-json\/wp\/v2\/media?parent=2148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}